{"id":805,"date":"2020-02-20T23:16:51","date_gmt":"2020-02-21T02:16:51","guid":{"rendered":"https:\/\/biosposadas.com\/productos\/venta\/microprocesador-intel-celeron-1-copy\/"},"modified":"2025-07-24T08:30:36","modified_gmt":"2025-07-24T11:30:36","slug":"procesador-intel-3ghz-socket-775","status":"publish","type":"product","link":"https:\/\/biosposadas.com\/productos\/venta\/procesador-intel-3ghz-socket-775\/","title":{"rendered":"Procesador Intel 3Ghz Socket 775"},"content":{"rendered":"<p><a href=\"https:\/\/wa.me\/5493764299305?text=Consulta%20desde%20el%20sitio%20web\" target=\"_blank\" rel=\"noopener noreferrer\"><\/p>\n<h3 style=\"text-align: center;\">Click! para ponerte en contacto!<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-115\" src=\"https:\/\/biosposadas.com\/productos\/wp-content\/uploads\/2020\/02\/wazap.png\" style=\"display: block; margin-left: auto; margin-right: auto;\" href=\"https:\/\/wa.me\/5493764299305?text=Consulta%20desde%20el%20sitio%20web\" target=\"_blank\" alt=\"\" width=\"300\" height=\"120\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>\n<h3>Pentium D 925<\/h3>\n<\/li>\n<li>\n<h4>3Ghz 4MB cache<\/h4>\n<\/li>\n<li>\n<h5>Socket 775<\/h5>\n<\/li>\n<ul>\n","protected":false},"featured_media":811,"template":"","meta":[],"product_brand":[],"product_cat":[54],"product_tag":[61],"class_list":["post-805","product","type-product","status-publish","has-post-thumbnail","product_cat-procesador","product_tag-intel","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/biosposadas.com\/productos\/wp-json\/wp\/v2\/product\/805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biosposadas.com\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/biosposadas.com\/productos\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biosposadas.com\/productos\/wp-json\/wp\/v2\/media\/811"}],"wp:attachment":[{"href":"https:\/\/biosposadas.com\/productos\/wp-json\/wp\/v2\/media?parent=805"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/biosposadas.com\/productos\/wp-json\/wp\/v2\/product_brand?post=805"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/biosposadas.com\/productos\/wp-json\/wp\/v2\/product_cat?post=805"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/biosposadas.com\/productos\/wp-json\/wp\/v2\/product_tag?post=805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}